{"id":1071,"date":"2025-07-23T17:41:51","date_gmt":"2025-07-23T15:41:51","guid":{"rendered":"https:\/\/windturbinemap.com\/?page_id=1071"},"modified":"2026-05-06T08:39:46","modified_gmt":"2026-05-06T06:39:46","slug":"wind-turbines-brandenburg-map","status":"publish","type":"page","link":"https:\/\/windturbinemap.com\/en\/windkraftanlagen-brandenburg-karte\/","title":{"rendered":"Wind power plants Brandenburg Map"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1071\" class=\"elementor elementor-1071\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-787dd18 e-flex e-con-boxed e-con e-parent\" data-id=\"787dd18\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2da1492 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"2da1492\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"832\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/01\/blurry-ASN1A6-985x1024-2.webp\" class=\"attachment-large size-large wp-image-644\" alt=\"blau verschwommener Hintergrund\" srcset=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/01\/blurry-ASN1A6-985x1024-2.webp 985w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/01\/blurry-ASN1A6-985x1024-2-289x300.webp 289w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/01\/blurry-ASN1A6-985x1024-2-768x798.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-181a3a9 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"181a3a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"773\" height=\"1024\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/01\/blurry-ASN1A7-1-773x1024.webp\" class=\"attachment-large size-large wp-image-653\" alt=\"hellblau unscharfer Hintergrund\" srcset=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/01\/blurry-ASN1A7-1-773x1024.webp 773w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/01\/blurry-ASN1A7-1-227x300.webp 227w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/01\/blurry-ASN1A7-1-768x1017.webp 768w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/01\/blurry-ASN1A7-1.webp 1024w\" sizes=\"(max-width: 773px) 100vw, 773px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36b1960 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"36b1960\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-cbdf8fc e-con-full e-flex e-con e-child\" data-id=\"cbdf8fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33330f9 rotate elementor-widget elementor-widget-image\" data-id=\"33330f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/wind-turbine-1.svg\" class=\"attachment-large size-large wp-image-107\" alt=\"Hellgr\u00fcne Turbine\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e61bca3 elementor-widget elementor-widget-heading\" data-id=\"e61bca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Windturbinen in Brandenburg\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-024b0ba elementor-widget elementor-widget-heading\" data-id=\"024b0ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Alle Windkraftanlagen in Brandenburg auf einer interaktiven Karte\u200b<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6acee8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a6acee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vom Fl\u00e4ming bis zur Uckermark \u2013 Brandenburg geh\u00f6rt zu den Vorreitern im Windkraftausbau. Unsere interaktive Karte zeigt jede Anlage, jedes Projekt, jede Entwicklung \u2013 visuell, datenbasiert und aktuell.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13dd8f6 elementor-widget__width-auto elementor-tablet-align-center elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"13dd8f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/map.windturbinemap.com\/?zoom=5.882282193947255&#038;center=14.98581%2C51.95336&#038;inbetriebnahmestartdatum=-2208988800&#038;inbetriebnahmeenddatum=null&#038;slider=Bruttoleistung+der+Einheit&#038;slidervals=0&#038;slidervale=15&#038;betriebs=In+Betrieb%2CIn+Planung%2CVor%C3%BCbergehend+stillgelegt%2CEndg%C3%BCltig+stillgelegt&#038;nachslider=Bundesland&#038;nach=Brandenburg\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Karte \u00f6ffnen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8435fa6 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"8435fa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1775\" height=\"976\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/07\/Bundesland-Brandenburg.png\" class=\"attachment-full size-full wp-image-1024\" alt=\"Kartenvorschau f\u00fcr Brandenburg von map.windturbinemap.com\" srcset=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/07\/Bundesland-Brandenburg.png 1775w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/07\/Bundesland-Brandenburg-300x165.png 300w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/07\/Bundesland-Brandenburg-1024x563.png 1024w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/07\/Bundesland-Brandenburg-768x422.png 768w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/07\/Bundesland-Brandenburg-1536x845.png 1536w\" sizes=\"(max-width: 1775px) 100vw, 1775px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-01ad00e e-flex e-con-boxed e-con e-parent\" data-id=\"01ad00e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-eb49e83 e-con-full e-flex e-con e-child\" data-id=\"eb49e83\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3852d5a e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3852d5a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-99da9c9 e-con-full e-flex e-con e-child\" data-id=\"99da9c9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c1a7e5 rotate elementor-widget elementor-widget-image\" data-id=\"8c1a7e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/wind-turbine-1.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce550bb elementor-widget elementor-widget-heading\" data-id=\"ce550bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenqualit\u00e4t, die \u00fcberzeugt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a84cfb elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"9a84cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bereinigte, gepr\u00fcfte und vernetzte Windkraftdaten f\u00fcr Brandenburg<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef4d9d7 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"ef4d9d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere Datenbank filtert, bereinigt und verkn\u00fcpft zusammengeh\u00f6rige Informationen. So erhalten Sie ein klares, nutzbares Bild vom tats\u00e4chlichen Windkraftgeschehen in Brandenburg \u2013 f\u00fcr Analysen, Antr\u00e4ge oder Recherchen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac7375b e-con-full e-flex e-con e-child\" data-id=\"ac7375b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cedb39d elementor-widget elementor-widget-image-carousel\" data-id=\"cedb39d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:1000,&quot;speed&quot;:800,&quot;slides_to_show&quot;:&quot;4&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:24,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;5&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_2-qxsr1e1jsdqggqyrnoekdideezcjok32qcf90isids.webp\" alt=\"Durch einen Direktvermarkter grunds\u00e4tzlich fernsteuerbar\" \/><figcaption class=\"elementor-image-carousel-caption\">Fernsteuerbarkeit Direktvermarkter<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_3-qxsr1e1jsdqggqyrnoekdideezcjok32qcf90isids.webp\" alt=\"Warnlicht nur bei Flugobjekten in der N\u00e4he (Bedarfsgerechte Nachtkennzeichung)\" \/><figcaption class=\"elementor-image-carousel-caption\">Nachtkennzeichung (BNK)<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_10-qxsr1gv2cvubfkuo77mg2zns74ynbne9qqdpgcobv4.webp\" alt=\"Zum Schutz vor Eiswurf Abschaltungen oder Leistungsbegrenzungen\" \/><figcaption class=\"elementor-image-carousel-caption\">Eiswurf Abschaltung<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_1-qxsr1d3pljp65504t5zxt0lxtlh6guzce7rrj8twk0.webp\" alt=\"Rotorblattenteisungssystem vorhanden\" \/><figcaption class=\"elementor-image-carousel-caption\">Rotorblatt-enteisung<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_5-qxsr1ezdz7rqscxei6t6y04v0d7ww96t2h2qhsr47k.webp\" alt=\"Prototyp (Erster Test eines neuen Modells)\" \/><figcaption class=\"elementor-image-carousel-caption\">Prototyp<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_9-qxsr1gv2cvubfkuo77mg2zns74ynbne9qqdpgcobv4.webp\" alt=\"Zum Tierschutz zeitweise Abschaltungen oder Leistungsbegrenzungen\" \/><figcaption class=\"elementor-image-carousel-caption\">Tierschutz Abschaltung<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_4-qxsr1ezdz7rqscxei6t6y04v0d7ww96t2h2qhsr47k.webp\" alt=\"Anlage von B\u00fcrgern finanziert (B\u00fcrgerenergie)\" \/><figcaption class=\"elementor-image-carousel-caption\">B\u00fcrgerenergie<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_8-qxsr1fx861t13yw1cp7tihwblr3a3yajelq7z2pq1c.webp\" alt=\"Zum Verhindern von st\u00f6rendem Schattenwurf zeitweise Abschaltungen\" \/><figcaption class=\"elementor-image-carousel-caption\">Schattenwurf Abschaltung<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_11-qxsr1hswjpvlr6tb1q12nhf8siu0jci02v16xmmxow.webp\" alt=\"Zum n\u00e4chtliche Schallimmissionsschutz\" \/><figcaption class=\"elementor-image-carousel-caption\">Nacht Abschaltung<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_6-qxsr1ezdz7rqscxei6t6y04v0d7ww96t2h2qhsr47k.webp\" alt=\"Pilotanlage (Test vor der Serienproduktion)\" \/><figcaption class=\"elementor-image-carousel-caption\">Pilotanlage<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_13-qxsr1hswjpvlr6tb1q12nhf8siu0jci02v16xmmxow.webp\" alt=\"Zum Schallimmissionsschutz tags\u00fcber\" \/><figcaption class=\"elementor-image-carousel-caption\">Schallimmissions-schutz<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_7-qxsr1fx861t13yw1cp7tihwblr3a3yajelq7z2pq1c.webp\" alt=\"Einsatzverantwortlicher\" \/><figcaption class=\"elementor-image-carousel-caption\">Einsatz-verantwortlicher<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/elementor\/thumbs\/WeitereDetails_12-qxsr1hswjpvlr6tb1q12nhf8siu0jci02v16xmmxow.webp\" alt=\"Abschaltung aus sonstigen Gr\u00fcnden\" \/><figcaption class=\"elementor-image-carousel-caption\">Sonstige Abschaltung<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6caa8e5 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"6caa8e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">mit umfangreicher Datentiefe<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84f90c0 e-con-full e-flex e-con e-child\" data-id=\"84f90c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c5b3585 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"c5b3585\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0f9d74 elementor-widget__width-initial elementor-widget elementor-widget-counter\" data-id=\"e0f9d74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"686\" data-from-value=\"15\" data-delimiter=\".\">15<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea520b9 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"ea520b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-01-ANCKA81.png\" class=\"attachment-large size-large wp-image-915\" alt=\"\" srcset=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-01-ANCKA81.png 512w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-01-ANCKA81-300x300.png 300w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-01-ANCKA81-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-598fadf elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"598fadf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">geplante Anlagen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7be4edf elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"7be4edf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alle aktuellen Vorhaben in Brandenburg \u2013 inklusive Genehmigungsstatus, Baujahr und Geokoordinaten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a563c10 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"a563c10\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae8434e elementor-widget__width-initial elementor-widget elementor-widget-counter\" data-id=\"ae8434e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+ <\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1200\" data-from-value=\"0\" data-delimiter=\".\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39b15c6 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"39b15c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-02-AJSJ881.png\" class=\"attachment-large size-large wp-image-916\" alt=\"\" srcset=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-02-AJSJ881.png 512w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-02-AJSJ881-300x300.png 300w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-02-AJSJ881-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-462297a elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"462297a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">aktive Betreiber in Brandenburg<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a49779b elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"a49779b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Erhalten Sie Zugriff auf strukturierte Betreiberdaten \u2013 von Genossenschaften bis zu internationalen Energieunternehmen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bef090b e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"bef090b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7af330c elementor-widget__width-initial elementor-widget elementor-widget-counter\" data-id=\"7af330c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+ <\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"4141\" data-from-value=\"0\" data-delimiter=\".\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f626c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a2f626c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-03-ANA8Z9.png\" class=\"attachment-large size-large wp-image-917\" alt=\"\" srcset=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-03-ANA8Z9.png 512w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-03-ANA8Z9-300x300.png 300w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2025\/06\/team-03-ANA8Z9-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-439d473 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"439d473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">bestehende Windenergieanlagen\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-163837e elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"163837e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jede Turbine mit Standort, Typenbezeichnung, Nabenh\u00f6he &amp; Inbetriebnahmedatum \u2013 tagesaktuell gepflegt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d9f444 e-flex e-con-boxed e-con e-parent\" data-id=\"1d9f444\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_blur_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;background_motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aeef813 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"aeef813\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1be2e75 e-con-full e-flex e-con e-child\" data-id=\"1be2e75\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f17391 rotate elementor-widget elementor-widget-image\" data-id=\"3f17391\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/wind-turbine-1.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-897cd95 elementor-widget elementor-widget-heading\" data-id=\"897cd95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Region im Fokus\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d586a6c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d586a6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Brandenburgs Windkraft \u2013 so transparent wie nie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30c2f8d elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"30c2f8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ob Beh\u00f6rdenarbeit, Projektplanung oder B\u00fcrgerbeteiligung: WindTurbineMap liefert exakte Standortdaten, Anlagendetails und Betreiberinfos f\u00fcr ganz Brandenburg. F\u00fcr bessere Entscheidungen und nachvollziehbare Energiewende.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48736b5 e-con-full e-flex e-con e-child\" data-id=\"48736b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4068de7 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"4068de7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e95512 elementor-widget elementor-widget-image\" data-id=\"9e95512\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"290\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/Sect_2_Hersteller-1.webp\" class=\"attachment-large size-large wp-image-113\" alt=\"Windenergieanlage Details\" srcset=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/Sect_2_Hersteller-1.webp 692w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/Sect_2_Hersteller-1-300x126.webp 300w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0ad1af e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"a0ad1af\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25a0943 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"25a0943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">WEA in Brandenburg auf einen Blick<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-725435e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"725435e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Planungsb\u00fcros, Journalisten oder engagierte B\u00fcrger \u2013 wer sich \u00fcber Windkraft in Brandenburg informieren will, findet hier die perfekte Grundlage f\u00fcr detaillierte Filterung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40ea3a2 elementor-widget elementor-widget-image\" data-id=\"40ea3a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"336\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/Sortierte_daten.webp\" class=\"attachment-large size-large wp-image-187\" alt=\"Filter Screenshot\" srcset=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/Sortierte_daten.webp 336w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/Sortierte_daten-300x300.webp 300w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/Sortierte_daten-150x150.webp 150w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd887b9 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"fd887b9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc43c2c elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"dc43c2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Smart filtern \u2013 pr\u00e4zise handeln<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6126c28 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6126c28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Suchen Sie nach Anlagen \u00fcber 3\u202fMW, bestimmten Herstellern oder einem Radius um Ihre Region? Unsere Filteroptionen bringen Klarheit in die Datenflut.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7950a1 elementor-widget elementor-widget-image\" data-id=\"b7950a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"338\" src=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/filter_daten.webp\" class=\"attachment-large size-large wp-image-188\" alt=\"Filter Auswahl Screenshot\" srcset=\"https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/filter_daten.webp 336w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/filter_daten-298x300.webp 298w, https:\/\/windturbinemap.com\/wp-content\/uploads\/2024\/11\/filter_daten-150x150.webp 150w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a2f6ba e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"2a2f6ba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbabbd0 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"cbabbd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eine Karte aller <a href=\"https:\/\/solarfarmmap.com\/solaranlagen-brandenburg-karte\/\" target=\"_blank\" rel=\"noopener\">Solaranlagen in Brandenburg<\/a> finden Sie auf SolarFarmMap.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Windturbinen in Brandenburg Alle Windkraftanlagen in Brandenburg auf einer interaktiven Karte\u200b Vom Fl\u00e4ming bis zur Uckermark \u2013 Brandenburg geh\u00f6rt zu den Vorreitern im Windkraftausbau. Unsere interaktive Karte zeigt jede Anlage, jedes Projekt, jede Entwicklung \u2013 visuell, datenbasiert und aktuell. Karte \u00f6ffnen Datenqualit\u00e4t, die \u00fcberzeugt Bereinigte, gepr\u00fcfte und vernetzte Windkraftdaten f\u00fcr Brandenburg Unsere Datenbank filtert, bereinigt [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1071","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/windturbinemap.com\/en\/wp-json\/wp\/v2\/pages\/1071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/windturbinemap.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/windturbinemap.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/windturbinemap.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/windturbinemap.com\/en\/wp-json\/wp\/v2\/comments?post=1071"}],"version-history":[{"count":10,"href":"https:\/\/windturbinemap.com\/en\/wp-json\/wp\/v2\/pages\/1071\/revisions"}],"predecessor-version":[{"id":1417,"href":"https:\/\/windturbinemap.com\/en\/wp-json\/wp\/v2\/pages\/1071\/revisions\/1417"}],"wp:attachment":[{"href":"https:\/\/windturbinemap.com\/en\/wp-json\/wp\/v2\/media?parent=1071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}